{"id":3441,"date":"2024-09-02T17:29:58","date_gmt":"2024-09-02T15:29:58","guid":{"rendered":"https:\/\/trueconf.com/es-es/blog\/?p=3441"},"modified":"2025-10-24T11:40:54","modified_gmt":"2025-10-24T09:40:54","slug":"trueconf-1-2-outlook","status":"publish","type":"post","link":"https:\/\/trueconf.com/es-es/blog\/actualizacion\/trueconf-1-2-outlook","title":{"rendered":"Nuevas caracter\u00edsticas del complemento TrueConf 1.2 para Microsoft Outlook"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"wp-image-40399 size-full\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/09\/outlook-es.jpg\" alt=\"\" width=\"1200\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">Nos complace lanzar el <b>TrueConf 1.2<\/b>, la \u00faltima actualizaci\u00f3n de nuestro complemento web para Microsoft Outlook (versi\u00f3n est\u00e1ndar). Ofrece la posibilidad de prohibir a los asistentes realizar comentarios de audio, seleccionar las categor\u00edas de usuarios que ingresar\u00e1n a la sala de espera al unirse a la conferencia, as\u00ed como otros cambios y mejoras \u00fatiles.<\/p>\n<p><!--more--><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">El complemento web de TrueConf para Microsoft Outlook se instala desde la tienda oficial de Outlook, su <a href=\"https:\/\/trueconf.com\/es-es\/blog\/noticias\/outlook-extended.html\" target=\"_blank\" rel=\"noopener\">versi\u00f3n extendida<\/a> se instala mediante un archivo MSI y tiene funciones m\u00e1s amplias<\/div>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a id=\"sbtn\" class=\"btn_blue btn_download big_text\" style=\"font-size: 23px;\" href=\"https:\/\/trueconf.com\/es-es\/caracteristicas\/integracion\/calendario.html\" target=\"_blank\" rel=\"noopener noreferrer\">Instalar<\/a><\/p>\n<p>&nbsp;<br \/>\n&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Deshabilitar comentarios de audio<\/h2>\n<p style=\"text-align: justify;\">Anteriormente en la <a href=\"https:\/\/trueconf.com\/es-es\/blog\/noticias\/trueconf-outlook-update-1-1.html\" target=\"_blank\" rel=\"noopener\">actualizaci\u00f3n del complemento de TrueConf para Microsoft Outlook<\/a>, admitimos salas de espera. Ahora tambi\u00e9n puede seleccionar las categor\u00edas de usuarios que ingresar\u00e1n a la sala de espera al unirse a la reuni\u00f3n:<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/09\/1.jpg\" data-rel=\"lightbox-gallery-0uZwoojh\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/09\/1.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Selecci\u00f3n de las categor\u00edas de usuarios que entran en la sala de espera<\/h2>\n<p style=\"text-align: justify;\">Earlier in the <a href=\"https:\/\/trueconf.com\/blog\/news\/trueconf-outlook-update-1-1.html\" target=\"_blank\" rel=\"noopener\">update of TrueConf add-in for Microsoft Outlook<\/a>, we supported waiting rooms. Now you can also select the categories of users who will enter the waiting room when joining the meeting:<\/p>\n<ul>\n<li>todos los participantes (excepto el propietario y los moderadores)<\/li>\n<li>participantes no programados<\/li>\n<li>participantes no programados de otros servidores.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/09\/2.jpg\" data-rel=\"lightbox-gallery-0uZwoojh\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/09\/2.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Otros cambios y mejoras \u00fatiles<\/h2>\n<ul>\n<li>Ahora puede ver una descripci\u00f3n detallada del tipo de conferencia seleccionado haciendo clic en el bot\u00f3n<img decoding=\"async\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/09\/info.jpg\" alt=\"\" width=\"26\" height=\"26\" class=\"alignnone size-full wp-image-56804\" loading=\"lazy\" title=\"\">  a la derecha del nombre del tipo, en la ventana de programaci\u00f3n de reuniones<\/li>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/09\/3.jpg\" data-rel=\"lightbox-gallery-0uZwoojh\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/09\/3.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<li>Hemos agregado la capacidad de cambiar de forma centralizada la configuraci\u00f3n del complemento de TrueConf para Microsoft Outlook mediante un archivo de configuraci\u00f3n<\/li>\n<li>Hemos agregado compatibilidad con los idiomas <b>espa\u00f1ol<\/b>, <b>portugu\u00e9s<\/b>, <b>italiano<\/b>, <b>alem\u00e1n<\/b>, <b>franc\u00e9s<\/b>, <b>polaco<\/b>, <b>checo<\/b>, <b>turcomano<\/b>, <b>coreano<\/b>, <b>japon\u00e9s<\/b>, <b>chino<\/b>, <b>vietnamita<\/b> y <b>azerbaiyano<\/b>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Nos complace lanzar el TrueConf 1.2, la \u00faltima actualizaci\u00f3n de nuestro complemento web para Microsoft Outlook (versi\u00f3n est\u00e1ndar). Ofrece la posibilidad de prohibir a los asistentes realizar comentarios de audio, seleccionar las categor\u00edas de usuarios que ingresar\u00e1n a la sala de espera al unirse a la conferencia, as\u00ed como otros cambios y mejoras \u00fatiles.<\/p>\n","protected":false},"author":57,"featured_media":3443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[31],"class_list":["post-3441","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualizacion","tag-microsoft-outlook","wpautop"],"_links":{"self":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/3441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/comments?post=3441"}],"version-history":[{"count":3,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/3441\/revisions"}],"predecessor-version":[{"id":3450,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/3441\/revisions\/3450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media\/3443"}],"wp:attachment":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media?parent=3441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/categories?post=3441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/tags?post=3441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}