{"id":3356,"date":"2024-07-31T10:59:07","date_gmt":"2024-07-31T08:59:07","guid":{"rendered":"https:\/\/trueconf.com/es-es/blog\/?p=3356"},"modified":"2025-10-24T11:41:22","modified_gmt":"2025-10-24T09:41:22","slug":"trueconf-server-5-4","status":"publish","type":"post","link":"https:\/\/trueconf.com/es-es/blog\/actualizacion\/trueconf-server-5-4","title":{"rendered":"Actualizaci\u00f3n mayor del TrueConf Server 5.4: traducci\u00f3n simult\u00e1nea, dise\u00f1os de video infinitos y nuevas funciones de mensajer\u00eda"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"wp-image-40399 size-full\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/es_tcs_1600x800_5.4.jpg\" alt=\"\" width=\"1200\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">Estamos encantados de presentar el <b>TrueConf Server 5.4<\/b>, una actualizaci\u00f3n importante de nuestra plataforma de colaboraci\u00f3n de video que cuenta con un nuevo modo de conferencia de traducci\u00f3n simult\u00e1nea, dise\u00f1os param\u00e9tricos que permiten implementar una cantidad infinita de escenarios de reuni\u00f3n, nuevas funciones de mensajer\u00eda, una extensi\u00f3n del tiempo de la conferencia sobre la marcha y mucho m\u00e1s. \u00a1Lea nuestra descripci\u00f3n detallada para obtener m\u00e1s informaci\u00f3n!<\/p>\n<p><!--more--><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">Actualizar al TrueConf Server 5.4 requiere volver a registrar su plataforma de colaboraci\u00f3n de video.<\/div>\n<p style=\"text-align: center;\"><a id=\"sbtn\" class=\"btn_blue btn_download big_text\" style=\"font-size: 23px;\" href=\"https:\/\/trueconf.com\/es-es\/blog\/base-de-conocimientos\/como-actualizar-trueconf-server.html\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bfC\u00f3mo actualizar el TrueConf Server?<\/a><\/p>\n<p><BR><\/p>\n<h2 style=\"text-align: justify;\">Sistemas operativos compatibles<\/h2>\n<ul>\n<li>Microsoft Windows Server 2008R2+<\/li>\n<li>Debian 12<\/li>\n<li>Debian 11<\/li>\n<li>CentOS Stream 9<\/li>\n<\/ul>\n<p><BR><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/trueconf.com\/support\/system-requirements.html#trueconf-server\" target=\"_blank\" rel=\"noopener\">Requisitos del sistema<\/a><\/p>\n<p><BR><\/p>\n<h2 style=\"text-align: justify;\">Nuevo modo: videoconferencias con traducci\u00f3n simult\u00e1nea<\/h2>\n<p style=\"text-align: justify;\">Hemos agregado un modo de interpretaci\u00f3n de idiomas para eventos y conferencias internacionales con participantes que hablan diferentes idiomas. Permite que int\u00e9rpretes profesionales en simult\u00e1neo se unan a reuniones en l\u00ednea, lo que proporciona a los participantes la posibilidad de escuchar a los oradores en su idioma preferido. Se puede habilitar la traducci\u00f3n simult\u00e1nea al crear una conferencia a trav\u00e9s del \u00e1rea personal del usuario, en las aplicaciones de cliente de escritorio y m\u00f3viles, as\u00ed como en el panel de control del TrueConf Server.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/1-1.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/1-1.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">La funci\u00f3n est\u00e1 disponible en:<br \/>\n\u2014 En TrueConf para Windows, Linux y macOS 8.4.1+<br \/>\n\u2014 En TrueConf para iOS\/iPadOS 3.6+<br \/>\n\u2014 En TrueConf para Android 3.0+.\n<\/div>\n<h3 style=\"text-align: justify;\">Int\u00e9rpretes<\/h3>\n<p style=\"text-align: justify;\">Para conferencias con traducci\u00f3n simult\u00e1nea, hemos introducido un nuevo rol de usuario: <b>int\u00e9rprete<\/b>. El propietario asigna los int\u00e9rpretes en la pesta\u00f1a <b>Interpretaci\u00f3n<\/b> al programar la conferencia. Para cada uno de ellos, se configura un par de idiomas con los idiomas de origen y de destino.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/2-1.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/2-1.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">Durante la conferencia, los participantes no ver\u00e1n a los int\u00e9rpretes. Los usuarios podr\u00e1n escucharlos seleccionando la pista de audio apropiada.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/3-1.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/3-1.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h3 style=\"text-align: justify;\">Interfaz del participante<\/h3>\n<p style=\"text-align: justify;\">En el panel inferior de la conferencia, de la aplicaci\u00f3n cliente o del navegador, los participantes de la conferencia pueden seleccionar r\u00e1pidamente los idiomas que desean escuchar.<\/p>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-3356 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/4-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/4-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/4-1.jpg 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/4-1-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/4-1-1024x575.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/4-1-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/4-1-1536x863.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/4-1-290x163.jpg 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/5-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1919\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/5-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/5-1.jpg 1919w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/5-1-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/5-1-1024x576.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/5-1-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/5-1-1536x864.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/5-1-290x163.jpg 290w\" sizes=\"auto, (max-width: 1919px) 100vw, 1919px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<p style=\"text-align: justify;\">El propietario y los moderadores de la conferencia tambi\u00e9n pueden cambiar manualmente las pistas de idioma y ajustar el volumen de los participantes mediante la <a href=\"https:\/\/docs.trueconf.com\/server\/en\/user\/conference-management\/\" target=\"_blank\" rel=\"noopener\">administraci\u00f3n de reuniones en tiempo real<\/a>.<\/p>\n<p><!-- \n\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.ru\/blog\/wp-content\/uploads\/2024\/06\/sinhroperevod.gif\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.ru\/blog\/wp-content\/uploads\/2024\/06\/sinhroperevod.gif\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n\n --><\/p>\n<h3 style=\"text-align: justify;\">Interfaz del int\u00e9rprete<\/h3>\n<p style=\"text-align: justify;\">Al conectarse a una conferencia, el int\u00e9rprete ve una ventana de control especial donde puede habilitar y deshabilitar r\u00e1pidamente el micr\u00f3fono y cambiar la pista de audio entrante y el idioma que traduce sobre la marcha, lo que permite involucrar a int\u00e9rpretes multiling\u00fces.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/6-2.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/6-2.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">La interfaz del int\u00e9rprete estar\u00e1 disponible solo para los usuarios de las aplicaciones cliente de escritorio TrueConf para Windows, Linux y macOS a partir de la versi\u00f3n 8.4.1+.<\/div>\n<h3 style=\"text-align: justify;\">Grabaci\u00f3n de la conferencia<\/h3>\n<p style=\"text-align: justify;\">Si la grabaci\u00f3n de una conferencia con interpretaci\u00f3n simult\u00e1nea est\u00e1 habilitada en el TrueConf Server, todas las pistas de idioma se guardar\u00e1n en el archivo de video final con la opci\u00f3n de cambiar posteriormente en un reproductor de video de terceros.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/7.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/7.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Ampliaci\u00f3n del tiempo de reuni\u00f3n sobre la marcha y recordatorio del fin de la conferencia<\/h2>\n<p style=\"text-align: justify;\">Con el TrueConf Server 5.4 ahora es posible ampliar el tiempo de la conferencia sin interrumpirla. El propietario y los moderadores pueden extender la reuni\u00f3n si se seleccion\u00f3 la opci\u00f3n <b>Habilitar extensi\u00f3n del tiempo de la conferencia<\/b> al programarla a trav\u00e9s del \u00e1rea personal del usuario, aplicaciones cliente de escritorio y m\u00f3viles, as\u00ed como en el panel de control del TrueConf Server.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/8.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/8.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-3356 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/9.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/9.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/9.jpg 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/9-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/9-1024x575.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/9-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/9-1536x863.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/9-290x163.jpg 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/10.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/10.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/10.jpg 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/10-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/10-1024x575.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/10-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/10-1536x863.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/10-290x163.jpg 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">La opci\u00f3n <b>Habilitar extensi\u00f3n del tiempo de la conferencia<\/b> est\u00e1 activa de forma predeterminada<\/div>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-3 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-3 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-3' class='gallery galleryid-3356 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/11.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-3\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/11.jpg 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/11-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/11-1024x575.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/11-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/11-1536x863.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/11-290x163.jpg 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/12.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-3\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/12.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/12.jpg 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/12-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/12-1024x575.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/12-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/12-1536x863.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/12-290x163.jpg 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<p style=\"text-align: justify;\">Para simplificar la gesti\u00f3n de las conferencias, hemos agregado una notificaci\u00f3n emergente con el recordatorio de finalizaci\u00f3n de la reuni\u00f3n; aparecer\u00e1 antes del final en el centro de notificaciones y en la gesti\u00f3n de reuniones en tiempo real.<\/p>\n<p style=\"text-align: justify;\">Puede configurar el momento en que aparece la notificaci\u00f3n del final de la conferencia al programar una reuni\u00f3n a trav\u00e9s del \u00e1rea personal del usuario, las aplicaciones cliente de escritorio y m\u00f3viles y en el panel de control del TrueConf Server.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/13.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/13.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">Las opciones de extensi\u00f3n del tiempo de reuni\u00f3n sobre la marcha y recordatorio de finalizaci\u00f3n de la conferencia est\u00e1n disponibles en las aplicaciones de escritorio de TrueConf para Windows, Linux y macOS a partir de la versi\u00f3n 8.4.1+<\/div>\n<h2 style=\"text-align: justify;\">Dise\u00f1os param\u00e9tricos<\/h2>\n<p style=\"text-align: justify;\">El editor de dise\u00f1o integrado ha experimentado mejoras significativas. Ahora puede realizar una reuni\u00f3n en l\u00ednea en cualquier escenario gracias a una configuraci\u00f3n a\u00fan m\u00e1s flexible de los dise\u00f1os de v\u00eddeo. Anteriormente, el dise\u00f1o se pod\u00eda llenar con ventanas de video con contenido y participantes seleccionados, ahora hemos agregado tres nuevos par\u00e1metros:<\/p>\n<ul>\n<li><b>Una ventana con un orador activo:<\/b> un mecanismo especial de activaci\u00f3n por voz (VAD) llevar\u00e1 a los participantes que hablan activamente al podio.<\/li>\n<li><b>La ventana con un participante aleatorio<\/b> la llena un participante seleccionado aleatoriamente.<\/li>\n<li><b>Una ventana con usuarios que se mezclan en el tiempo<\/b>: los participantes seleccionados al azar que no pertenecen a otros tipos de ventanas se alternar\u00e1n seg\u00fan los par\u00e1metros establecidos en la configuraci\u00f3n de <b>Mezcla aleatoria<\/b>. Est\u00e1 disponible solo al editar el dise\u00f1o en los modos <b>Reuni\u00f3n Inteligente<\/b> y <b>Todos en pantalla<\/b>.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-4 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-4 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-4' class='gallery galleryid-3356 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/14.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-4\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1919\" height=\"1077\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/14.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/14.jpg 1919w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/14-690x387.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/14-1024x575.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/14-768x431.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/14-1536x862.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/14-290x163.jpg 290w\" sizes=\"auto, (max-width: 1919px) 100vw, 1919px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/15.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-4\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1919\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/15.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/15.jpg 1919w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/15-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/15-1024x576.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/15-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/15-1536x864.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/15-290x163.jpg 290w\" sizes=\"auto, (max-width: 1919px) 100vw, 1919px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<p style=\"text-align: justify;\">Puede configurar ventanas de v\u00eddeo, tanto al programar una conferencia como durante la misma, utilizando la gesti\u00f3n de reuniones en tiempo real.<\/p>\n<h3 style=\"text-align: justify;\">Mezclar ventanas en el dise\u00f1o<\/h3>\n<p style=\"text-align: justify;\">Para ventanas de video con <b>mezcla de usuarios en el tiempo<\/b>, puede configurar los ajustes para mezclar participantes:<\/p>\n<ul>\n<li>mezcla aleatoria<\/li>\n<li>mezcla por intervalos<\/li>\n<li>mezcla por tipo:<\/li>\n<ul>\n<li> \u2014 reemplazo: los participantes ser\u00e1n reemplazados por otros usuarios aleatorios.<\/li>\n<li> \u2014 en movimiento: los participantes ser\u00e1n trasladados a un espacio adyacente con <b>Mezcla en el tiempo<\/b>. Funcionar\u00e1 si hay dos o m\u00e1s ventanas de v\u00eddeo de este tipo.<\/li>\n<\/ul>\n<\/ul>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/16.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/16.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Comentarios de audio deshabilitados<\/h2>\n<p style=\"text-align: justify;\">En el modo <b>Moderada basada en roles<\/b>, el propietario puede impedir que los oyentes hagan comentarios de audio breves; en este caso, el bot\u00f3n <b>Pulsar para hablar<\/b> no estar\u00e1 disponible durante la conferencia. Puede hacer esto al programar una conferencia p\u00fablica o privada en la pesta\u00f1a <b>Avanzado<\/b> en el \u00e1rea personal del usuario, en las aplicaciones cliente de escritorio y m\u00f3viles, as\u00ed como en el panel de control del TrueConf Server.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/17.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/17.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Marca en la reuni\u00f3n <\/h2>\n<p style=\"text-align: justify;\">El administrador del TrueConf Server 5.4 puede personalizar la conferencia agregando una imagen de fondo y un logotipo; se mostrar\u00e1n durante una sesi\u00f3n de transmisi\u00f3n y en las grabaciones de la reuni\u00f3n, as\u00ed como para los usuarios que se conectaron a la conferencia a trav\u00e9s de un navegador y terminales SIP\/H.323. Puede cambiar el fondo y el logotipo en la secci\u00f3n <b>Gateways \u2014 Transcodificaci\u00f3n \u2014 Dise\u00f1o de la conferencia<\/b> en el panel de control del TrueConf Server.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/18.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/18.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Compatibilidad con VP8 para conexiones SIP<\/h2>\n<p style=\"text-align: justify;\">En el TrueConf Server 5.4, agregamos soporte para el c\u00f3dec de video VP8 para conexiones SIP. Ayuda a optimizar el consumo de tr\u00e1fico y tambi\u00e9n permite mantener una alta calidad de audio y video incluso con una conexi\u00f3n a Internet inestable.<\/p>\n<h2 style=\"text-align: justify;\">Soporte de transmisi\u00f3n simult\u00e1nea para conexiones WebRTC<\/h2>\n<p style=\"text-align: justify;\">Tambi\u00e9n hemos agregado soporte para la tecnolog\u00eda Simulcast para conexiones WebRTC. Esto ha reducido la carga en el canal de red de los usuarios que se conectan a videoconferencias a trav\u00e9s de un navegador, manteniendo al mismo tiempo v\u00eddeo y audio de alta calidad.<\/p>\n<h2 style=\"font-size: 155%;\">Nuevas funciones de mensajer\u00eda<\/h2>\n<h3 style=\"text-align: justify;\">Sincronizaci\u00f3n de borradores<\/h3>\n<p style=\"text-align: justify;\">A partir del TrueConf Server 5.4, los usuarios de aplicaciones cliente m\u00f3viles y de escritorio podr\u00e1n editar borradores en chats desde cualquier dispositivo en el que hayan iniciado sesi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-5 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-5 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-5 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-5 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-5' class='gallery galleryid-3356 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/19.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-5\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1919\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/19.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/19.jpg 1919w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/19-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/19-1024x576.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/19-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/19-1536x864.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/19-290x163.jpg 290w\" sizes=\"auto, (max-width: 1919px) 100vw, 1919px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/20.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-5\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1919\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/20.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/20.jpg 1919w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/20-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/20-1024x576.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/20-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/20-1536x864.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/20-290x163.jpg 290w\" sizes=\"auto, (max-width: 1919px) 100vw, 1919px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">La funci\u00f3n est\u00e1 disponible:<br \/>\n\u2014 En TrueConf para Windows, Linux y macOS 8.4.1+<br \/>\n\u2014 En TrueConf para iOS\/iPadOS 3.6+<br \/>\n\u2014 En TrueConf para Android 3.0+.\n<\/div>\n<h3 style=\"text-align: justify;\">Estado \u00abEscribiendo&#8230;\u00bb<\/h3>\n<p style=\"text-align: justify;\">En la lista de chats, as\u00ed como en los chats personales o grupales, ahora puedes ver el estado <b>\u00abEscribiendo&#8230;\u00bb<\/b> junto a los nombres de los usuarios que actualmente est\u00e1n escribiendo un mensaje.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/21.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/21.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">La funci\u00f3n est\u00e1 disponible:<br \/>\n\u2014 En TrueConf para Windows, Linux y macOS 8.4.1+<br \/>\n\u2014 En TrueConf para iOS\/iPadOS 3.6+<br \/>\n\u2014 En TrueConf para Android 3.0+.\n<\/div>\n<h3 style=\"text-align: justify;\">Informaci\u00f3n sobre la lectura del mensaje<\/h3>\n<p style=\"text-align: justify;\">A partir del TrueConf Server 5.4, los usuarios de aplicaciones cliente m\u00f3viles y de escritorio ahora pueden ver qui\u00e9n de los participantes del chat grupal vio el mensaje que enviaron.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/22.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/22.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">La funci\u00f3n est\u00e1 disponible:<br \/>\n\u2014 En TrueConf para Windows, Linux y macOS 8.4.1+<br \/>\n\u2014 En TrueConf para iOS\/iPadOS 3.6+<br \/>\n\u2014 En TrueConf para Android 3.0+.\n<\/div>\n<h3 style=\"text-align: justify;\">Chat \u00abFavoritos\u00bb<\/h3>\n<p style=\"text-align: justify;\">Cada usuario tiene su propio chat <b>Favoritos<\/b>, que puede utilizarse como un almacenamiento personal de archivos y mensajes \u00fatiles. Simplemente haga clic en <b>Reenviar<\/b> en el mensaje que necesita y seleccione <b>Favoritos<\/b> de la lista de contactos.<\/p>\n<p style=\"text-align: justify;\">Al hacer clic en el bot\u00f3n <img decoding=\"async\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/image-1.png\" alt=\"\" width=\"20\" height=\"20\" class=\"alignnone size-full wp-image-55371\" loading=\"lazy\" title=\"\"> en el panel Chats, puede crear el chat Favoritos o navegar hasta \u00e9l.<\/p>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-6 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-6 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-6 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-6 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-6' class='gallery galleryid-3356 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/23.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-6\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1943\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/23.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/23.jpg 1943w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/23-690x383.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/23-1024x569.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/23-768x426.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/23-1536x853.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/23-290x161.jpg 290w\" sizes=\"auto, (max-width: 1943px) 100vw, 1943px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/24.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-6\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1919\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/24.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/24.jpg 1919w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/24-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/24-1024x576.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/24-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/24-1536x864.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/24-290x163.jpg 290w\" sizes=\"auto, (max-width: 1919px) 100vw, 1919px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">La funci\u00f3n est\u00e1 disponible:<br \/>\n\u2014 En TrueConf para Windows, Linux y macOS 8.4.1+<br \/>\n\u2014 En TrueConf para iOS\/iPadOS 3.6+<br \/>\n\u2014 En TrueConf para Android 3.0+.\n<\/div>\n<h2 style=\"text-align: justify;\">Nuevas funciones de chat en el navegador<\/h2>\n<p style=\"text-align: justify;\">Hemos ampliado las capacidades del chat de la conferencia para los participantes que se unen mediante un navegador. Ahora los usuarios pueden:<\/p>\n<ul>\n<li>reenviar uno o varios mensajes<\/li>\n<li>responder a mensajes<\/li>\n<li>seleccionar varios mensajes<\/li>\n<li>editar mensajes enviados<\/li>\n<li>copiar el texto del mensaje<\/li>\n<li>borrar sus propios mensajes<\/li>\n<li>ver la cantidad de mensajes no le\u00eddos en el chat<\/li>\n<li>cargar, ver y descargar archivos adjuntos.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-7 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-7 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-7 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-7 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-7' class='gallery galleryid-3356 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/25.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-7\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1928\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/25.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/25.jpg 1928w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/25-690x386.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/25-1024x573.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/25-768x430.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/25-1536x860.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/25-290x162.jpg 290w\" sizes=\"auto, (max-width: 1928px) 100vw, 1928px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/26.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-7\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1919\" height=\"1079\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/26.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/26.jpg 1919w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/26-690x388.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/26-1024x576.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/26-768x432.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/26-1536x864.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2024\/07\/26-290x163.jpg 290w\" sizes=\"auto, (max-width: 1919px) 100vw, 1919px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s del chat de la conferencia, ahora hay disponible un chat personal en el navegador; puede acceder a \u00e9l haciendo clic en el nombre del usuario en el chat de la reuni\u00f3n o en la lista de participantes.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/27.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/27.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Deshabilitar el uso de determinadas aplicaciones<\/h2>\n<p style=\"text-align: justify;\">El administrador del TrueConf Server 5.4 ahora puede deshabilitar la autorizaci\u00f3n en las aplicaciones cliente TrueConf para usuarios de sistemas operativos seleccionados en la secci\u00f3n <b>Configuraci\u00f3n \u2014 Aplicaci\u00f3n<\/b>. Adem\u00e1s, ahora es posible configurar versiones de aplicaciones cliente que determinar\u00e1n la necesidad de actualizaciones para los usuarios de Linux, macOS, Android e iOS.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/28.jpg\" data-rel=\"lightbox-gallery-7JmUfHLw\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2024\/07\/28.jpg\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Otros cambios y mejoras \u00fatiles<\/h2>\n<ul>\n<li>La velocidad de fotogramas para cada usuario de la conferencia grupal se ha aumentado a 30 fps<\/li>\n<li>Se ha agregado la capacidad de deshabilitar el compartir contenido de usuarios seleccionados<\/li>\n<li>Agregamos la grabaci\u00f3n de conferencias y videollamadas en .WEBM <\/li>\n<li>Se ha aumentado la velocidad de sincronizaci\u00f3n del chat despu\u00e9s de la autorizaci\u00f3n del usuario en la aplicaci\u00f3n cliente<\/li>\n<li>Hemos agregado la capacidad de configurar el gateway SIP\/H323 para redirigir al usuario al men\u00fa de entrada de ID de conferencia cuando llama a la direcci\u00f3n IP o FQDN del servidor<\/li>\n<li>El n\u00famero m\u00e1ximo de contactos personales en la libreta de direcciones del usuario se ha aumentado a 300 usuarios<\/li>\n<li>Hemos agregado una indicaci\u00f3n de grabaci\u00f3n habilitada en el TrueConf Server para videos mixtos enviados a terminales SIP\/H.323<\/li>\n<li>Agregamos la capacidad de cargar avatares y enviar im\u00e1genes comprimidas en .WEBP<\/li>\n<li>Se ha mejorado el rendimiento general y la estabilidad de la plataforma de colaboraci\u00f3n de v\u00eddeo<\/li>\n<li>Hemos mejorado significativamente la eficiencia del env\u00edo de datos de audio y video dentro de una conferencia<\/li>\n<\/ul>\n<p>Para obtener una lista completa de actualizaciones, consulte nuestro <a href=\"https:\/\/trueconf.com\/es-es\/productos\/changelog.html#server\" target=\"_blank\" rel=\"noopener\">notas de lanzamiento<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos encantados de presentar el TrueConf Server 5.4, una actualizaci\u00f3n importante de nuestra plataforma de colaboraci\u00f3n de video que cuenta con un nuevo modo de conferencia de traducci\u00f3n simult\u00e1nea, dise\u00f1os param\u00e9tricos que permiten implementar una cantidad infinita de escenarios de reuni\u00f3n, nuevas funciones de mensajer\u00eda, una extensi\u00f3n del tiempo de la conferencia sobre la marcha [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":3387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[3],"class_list":["post-3356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualizacion","tag-trueconf-server","wpautop"],"_links":{"self":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/3356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/comments?post=3356"}],"version-history":[{"count":5,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/3356\/revisions"}],"predecessor-version":[{"id":3395,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/3356\/revisions\/3395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media\/3387"}],"wp:attachment":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media?parent=3356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/categories?post=3356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/tags?post=3356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}