{"id":2927,"date":"2023-11-01T11:20:07","date_gmt":"2023-11-01T10:20:07","guid":{"rendered":"https:\/\/trueconf.com/es-es/blog\/?p=2927"},"modified":"2025-10-28T12:24:56","modified_gmt":"2025-10-28T11:24:56","slug":"trueconf-server-5-3","status":"publish","type":"post","link":"https:\/\/trueconf.com/es-es/blog\/actualizacion\/trueconf-server-5-3","title":{"rendered":"Actualizaci\u00f3n importante del TrueConf Server 5.3: nuevo licenciamiento, extensiones de correo y soporte para Debian 12"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"wp-image-40399 size-full\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/tcs_1600x800_es.jpg\" alt=\"\" width=\"1200\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">Estamos felices de anunciar el <b>TrueConf Server 5.3<\/b>, la \u00faltima actualizaci\u00f3n de nuestra soluci\u00f3n insignia, que hace que el sistema de mensajer\u00eda corporativo est\u00e9 a\u00fan m\u00e1s disponible debido a una pol\u00edtica de licencias completamente renovada. Adem\u00e1s, la nueva versi\u00f3n introduce una nueva secci\u00f3n para gestionar extensiones de correo, funciones avanzadas de salas de espera y soporte para Debian 12.<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: center;\"><a id=\"sbtn\" class=\"btn_blue btn_download big_text\" style=\"font-size: 23px;\" href=\"https:\/\/trueconf.com\/download\/server\/windows\/trueconf_server_setup.exe\" target=\"_blank\" rel=\"noopener noreferrer\">Actualizaci\u00f3n para Windows<\/a><\/p>\n<p style=\"text-align: center;\"><a id=\"sbtn\" class=\"btn_blue btn_download big_text\" style=\"font-size: 23px;\" href=\"https:\/\/trueconf.com\/blog\/knowledge-base\/install-and-set-up-your-video-conferencing-server-for-linux-in-15-minutes.html#Step_3_Install_TrueConf_Server_for_Linux\" target=\"_blank\" rel=\"noopener noreferrer\">Actualizaci\u00f3n para Linux<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Lista de los sistemas operativos compatibles<\/h2>\n<ul>\n<li>Microsoft Windows Server 2008R2+<\/li>\n<li><b>Nuevo<\/b>: Debian 12<\/li>\n<li>Debian 11<\/li>\n<li>Debian 10<\/li>\n<li><b>Nuevo<\/b>: CentOS 9<\/li>\n<\/ul>\n<h2 style=\"font-size: 155%;\">Nuevo licenciamiento<\/h2>\n<h3 style=\"text-align: justify;\">Caracter\u00edsticas de la versi\u00f3n gratuita<\/h3>\n<p style=\"text-align: justify;\">En el <a href=\"https:\/\/trueconf.com\/products\/tcsf\/trueconf-server-free.html\" target=\"_blank\" rel=\"noopener\">TrueConf Server Free<\/a>, hasta 50 usuarios pueden comunicarse en chats grupales y personales, as\u00ed como realizar llamadas uno a uno, mientras que en conferencias grupales pueden participar hasta 10 usuarios simult\u00e1neos. Esto permitir\u00e1 utilizar la plataforma de videocolaboraci\u00f3n como un sistema de mensajer\u00eda corporativo, asequible, con capacidades para videoconferencias.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, el TrueConf Server Free actualizado proporciona integraci\u00f3n con Active Directory o cualquier otro directorio LDAP, para la sincronizaci\u00f3n autom\u00e1tica de libretas de direcciones, de forma gratuita.<\/p>\n<h3 style=\"text-align: justify;\">Licencias PRO<\/h3>\n<p style=\"text-align: justify;\">A partir del TrueConf Server 5.3, los nuevos <b>usuarios PRO<\/b> pueden participar en conferencias y todas las dem\u00e1s funciones est\u00e1n disponibles para los <b>usuarios en l\u00ednea<\/b>, cuyo precio se ha vuelto mucho m\u00e1s bajo.<\/p>\n<p style=\"text-align: justify;\">Las licencias en l\u00ednea se toman autom\u00e1ticamente cuando el usuario est\u00e1 autorizado en el dispositivo y las licencias PRO se toman cuando los usuarios participan en conferencias grupales o se pueden asignar a un grupo de usuarios de forma permanente. Las licencias PRO se gestionan en el apartado correspondiente.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/1.jpg\" data-rel=\"lightbox-gallery-7sUBBLD1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/1.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">La autorizaci\u00f3n en N dispositivos requerir\u00e1 N licencias en l\u00ednea. La autorizaci\u00f3n de un usuario PRO tambi\u00e9n requiere autom\u00e1ticamente una licencia en l\u00ednea.<\/div>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">Por cada <b>2 licencias PRO<\/b> compradas, recibir\u00e1 <b>3 licencias online<\/b>. Tambi\u00e9n es posible comprar licencias en l\u00ednea adicionales en paquetes de 50, 100, 200, 300, 400 y 500.<\/div>\n<h3 style=\"text-align: justify;\">Licencias permanentes y temporales<\/h3>\n<p style=\"text-align: justify;\">El administrador del TrueConf Server puede otorgar licencias PRO a grupos de usuarios seleccionados, dichas licencias se consideran permanentes y se asignan sin l\u00edmites de tiempo. Otros usuarios, al participar en conferencias grupales, tomar\u00e1n licencias temporales que se les otorgan por 24 horas. Si el usuario se une a otras conferencias grupales durante este per\u00edodo, la licencia se renovar\u00e1 por otras 24 horas a partir del momento en el que abandone la conferencia.<\/p>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-2927 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/2.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1872\" height=\"891\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/2.jpg 1872w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/2-690x328.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/2-1024x487.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/2-768x366.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/2-1536x731.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/2-290x138.jpg 290w\" sizes=\"auto, (max-width: 1872px) 100vw, 1872px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/3.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1872\" height=\"891\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/3.jpg 1872w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/3-690x328.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/3-1024x487.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/3-768x366.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/3-1536x731.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/3-290x138.jpg 290w\" sizes=\"auto, (max-width: 1872px) 100vw, 1872px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">Los cambios realizados en la lista de grupos de usuarios con licencias permanentes se aplican cada 24 horas desde el momento en que se inicia o reinicia el TrueConf Server.<\/div>\n<p style=\"text-align: justify;\">El administrador del TrueConf Server 5.3 puede configurar la <b>visualizaci\u00f3n<\/b> de informaci\u00f3n sobre la licencia PRO en las aplicaciones cliente de TrueConf, as\u00ed como habilitar o deshabilitar la capacidad de los usuarios para solicitar licencias PRO temporales.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/4.jpg\" data-rel=\"lightbox-gallery-7sUBBLD1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/4.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-2927 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/5.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1017\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/5.jpg 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/5-690x365.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/5-1024x542.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/5-768x407.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/5-1536x814.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/5-290x154.jpg 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/6.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1017\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/6.jpg 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/6-690x365.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/6-1024x542.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/6-768x407.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/6-1536x814.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/6-290x154.jpg 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Hemos descrito en detalle el nuevo licenciamiento en nuestro <a href=\"https:\/\/www.youtube.com\/watch?v=khOY9gS8eo8\" target=\"_blank\" rel=\"noopener\">seminario web<\/a> bajo demanda, as\u00ed como en la <a href=\"https:\/\/docs.trueconf.com\/server\/en\/admin\/license\/\" target=\"_blank\" rel=\"noopener\">documentaci\u00f3n del TrueConf Server<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"font-size: 155%;\">Extensiones de correo<\/h2>\n<p style=\"text-align: justify;\">En el TrueConf Server 5.3, hemos agregado una secci\u00f3n especial que le permite configurar las extensiones de correo de Microsoft Outlook y Mozilla Thunderbird.<\/p>\n<h3 style=\"text-align: justify;\">Complemento web de Microsoft Outlook<\/h3>\n<p style=\"text-align: justify;\">Ahora puede agregar el complemento web de Microsoft Outlook al TrueConf Server para poder distribuirlo entre los usuarios registrados. El administrador puede compartirlo con los usuarios, tanto en un archivo listo para instalar, como en un enlace para descargarlo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/7.jpg\" data-rel=\"lightbox-gallery-7sUBBLD1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/7.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">Instrucciones sobre c\u00f3mo los usuarios pueden instalar el <a href=\"https:\/\/trueconf.com\/blog\/knowledge-base\/how-outlook-users-can-install-trueconf-add-on.html\" target=\"_blank\" rel=\"noopener\">complemento web de TrueConf para Microsoft Outlook<\/a><\/div>\n<h3 style=\"text-align: justify;\">Complemento de Windows para Microsoft Outlook<\/h3>\n<p style=\"text-align: justify;\">En la nueva secci\u00f3n de <b>extensiones de correo<\/b>, puede compartir con los usuarios del TrueConf Server un enlace para descargar el <a href=\"https:\/\/trueconf.com\/blog\/knowledge-base\/how-outlook-users-can-install-trueconf-add-on.html#Desktop_version_installation\" target=\"_blank\" rel=\"noopener\">complemento de Windows<\/a> extendido para Microsoft Outlook, que tiene capacidades de planificaci\u00f3n de conferencias m\u00e1s flexibles.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/8.jpg\" data-rel=\"lightbox-gallery-7sUBBLD1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/8.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">Instrucciones sobre c\u00f3mo los usuarios pueden instalar la <a href=\"https:\/\/trueconf.com\/blog\/knowledge-base\/how-outlook-users-can-install-trueconf-add-on.html#Desktop_version_installation\" target=\"_blank\" rel=\"noopener\">versi\u00f3n de Windows del complemento de TrueConf para Microsoft Outlook<\/a><\/div>\n<h3 style=\"text-align: justify;\">Complemento de Mozilla Thunderbird<\/h3>\n<p style=\"text-align: justify;\">Los administradores tambi\u00e9n pueden compartir con los usuarios un enlace para descargar el complemento para Mozilla Thunderbird en .XPI.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/9.jpg\" data-rel=\"lightbox-gallery-7sUBBLD1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/9.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">Instrucciones sobre c\u00f3mo los usuarios pueden instalar el <a href=\"https:\/\/trueconf.com\/blog\/knowledge-base\/how-outlook-users-can-install-trueconf-add-on.html#Desktop_version_installation\" target=\"_blank\" rel=\"noopener\">complemento de TrueConf para Mozilla Thunderbird<\/a><\/a><\/div>\n<h3 style=\"text-align: justify;\">Configurar la plantilla de invitaci\u00f3n a la conferencia<\/h3>\n<p style=\"text-align: justify;\">El administrador del TrueConf Server ahora puede configurar una plantilla de descripci\u00f3n para una reuni\u00f3n creada con complementos TrueConf para Microsoft Outlook y Mozilla Thunderbird.<\/p>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-3 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-3 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-3' class='gallery galleryid-2927 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/10.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-3\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1872\" height=\"891\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/10.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/10.jpg 1872w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/10-690x328.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/10-1024x487.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/10-768x366.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/10-1536x731.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/10-290x138.jpg 290w\" sizes=\"auto, (max-width: 1872px) 100vw, 1872px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/11.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-3\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1872\" height=\"891\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/11.jpg 1872w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/11-690x328.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/11-1024x487.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/11-768x366.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/11-1536x731.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/11-290x138.jpg 290w\" sizes=\"auto, (max-width: 1872px) 100vw, 1872px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"font-size: 155%;\">Funciones avanzadas de las salas de espera<\/h2>\n<h3 style=\"text-align: justify;\">Selecci\u00f3n de categor\u00edas de usuarios, accediendo a la sala de espera<\/h3>\n<p style=\"text-align: justify;\">En el <a href=\"https:\/\/trueconf.com\/es-es\/blog\/noticias\/trueconf-server-5-2-9.html\" target=\"_blank\" rel=\"noopener\">TrueConf Server 5.2.9<\/a>, introdujimos salas de espera, un mecanismo que le permite distribuir a los participantes conectados entre una videoconferencia en ejecuci\u00f3n y una sala de espera. Ahora, al crear una conferencia, podr\u00e1 seleccionar las categor\u00edas de usuarios que ser\u00e1n dirigidos a la sala de espera al conectarse a la reuni\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/12.jpg\" data-rel=\"lightbox-gallery-7sUBBLD1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/12.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h3 style=\"text-align: justify;\">Habilitar y deshabilitar salas de espera sobre la marcha<\/h3>\n<p style=\"text-align: justify;\">Los operadores de las conferencias ahora pueden habilitar y deshabilitar la sala de espera en la conferencia en curso sobre la marcha, simplemente haciendo click en el bot\u00f3n correspondiente en la secci\u00f3n de administraci\u00f3n de conferencias en las aplicaciones cliente TrueConf para Windows, Linux, macOS e iOS, as\u00ed como en la <a href=\"https:\/\/www.youtube.com\/watch?v=rnmemPmPteE\" target=\"_blank\" rel=\"noopener\">gesti\u00f3n avanzada de las conferencias<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-4 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-4 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-4 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-4' class='gallery galleryid-2927 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/13.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-4\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1919\" height=\"1017\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/13.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/13.jpg 1919w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/13-690x366.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/13-1024x543.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/13-768x407.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/13-1536x814.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/13-290x154.jpg 290w\" sizes=\"auto, (max-width: 1919px) 100vw, 1919px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/14.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-4\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1017\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/14.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/14.jpg 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/14-690x365.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/14-1024x542.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/14-768x407.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/14-1536x814.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/14-290x154.jpg 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Eliminaci\u00f3n autom\u00e1tica de conferencias<\/h2>\n<p style=\"text-align: justify;\">El administrador ahora puede habilitar y configurar la eliminaci\u00f3n autom\u00e1tica de las conferencias programadas finalizadas y salas virtuales no iniciadas.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/15.jpg\" data-rel=\"lightbox-gallery-7sUBBLD1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/15.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Nuevos filtros en la lista de las conferencias<\/h2>\n<p style=\"text-align: justify;\">En el TrueConf Server 5.3, agregamos nuevos filtros a la lista de conferencias. Ahora, adem\u00e1s de buscar por tema, propietario y participante, puede ordenar las conferencias por <b>modo<\/b>, <b>tipo<\/b> y <b>fuente<\/b>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/16.jpg\" data-rel=\"lightbox-gallery-7sUBBLD1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/16.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Visualizaci\u00f3n del historial de reuniones recurrentes y salas virtuales<\/h2>\n<p style=\"text-align: justify;\">Para salas virtuales y conferencias programadas recurrentes, ahora puede ver el <b>historial de llamadas<\/b>, el bot\u00f3n correspondiente se muestra en la tarjeta del evento seleccionado en la lista de las conferencias.<\/p>\n<p style=\"text-align: justify;\">\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-5 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-5 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-5 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-5 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-5' class='gallery galleryid-2927 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/17.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-5\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1872\" height=\"891\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/17.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/17.jpg 1872w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/17-690x328.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/17-1024x487.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/17-768x366.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/17-1536x731.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/17-290x138.jpg 290w\" sizes=\"auto, (max-width: 1872px) 100vw, 1872px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/18.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-5\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1872\" height=\"891\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/18.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/18.jpg 1872w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/18-690x328.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/18-1024x487.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/18-768x366.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/18-1536x731.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/18-290x138.jpg 290w\" sizes=\"auto, (max-width: 1872px) 100vw, 1872px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/p>\n<h2 style=\"text-align: justify;\">Minimizar la tarjeta de la conferencia<\/h2>\n<p style=\"text-align: justify;\">En el TrueConf Server 5.3, agregamos la capacidad de minimizar la tarjeta de la conferencia, lo que permitir\u00e1 usar el espacio de trabajo de manera m\u00e1s eficiente y aumentar\u00e1 la comodidad al trabajar con la lista de las conferencias.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/es.gif\" data-rel=\"lightbox-gallery-7sUBBLD1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/es.gif\" alt=\"\" width=\"1600\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Otras mejoras \u00fatiles<\/h2>\n<ul>\n<li>Se ha mejorado el rendimiento de la plataforma de colaboraci\u00f3n de v\u00eddeo cuando un gran n\u00famero de usuarios participan simult\u00e1neamente en conferencias a trav\u00e9s de un navegador<\/li>\n<li>Hemos agregado un indicador de grabaci\u00f3n de conferencias habilitado en el TrueConf Server para usuarios de aplicaciones cliente de escritorio, as\u00ed como para usuarios que participan en conferencias usando un navegador<br \/>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-6 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-6 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-6 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-6 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-6' class='gallery galleryid-2927 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/19.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-6\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"988\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/19.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/19.jpg 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/19-690x355.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/19-1024x527.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/19-768x395.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/19-1536x790.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/19-290x149.jpg 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/20-1.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-6\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1921\" height=\"989\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/20-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/20-1.jpg 1921w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/20-1-690x355.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/20-1-1024x527.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/20-1-768x395.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/20-1-1536x791.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/11\/20-1-290x149.jpg 290w\" sizes=\"auto, (max-width: 1921px) 100vw, 1921px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n<\/li>\n<li>La p\u00e1gina de la conferencia ahora muestra informaci\u00f3n sobre el tipo y modo de la conferencia\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/21.jpg\" data-rel=\"lightbox-gallery-7sUBBLD1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es-es\/blog\/wp-content\/uploads\/2023\/11\/21.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<\/li>\n<li>En la gesti\u00f3n avanzada de las conferencias, ahora puede ajustar el volumen de los usuarios que participan en una conferencia mediante un navegador<\/li>\n<li>La informaci\u00f3n sobre las notificaciones deshabilitadas en los chats seleccionados de un usuario ahora se sincroniza en m\u00faltiples dispositivos autorizados<\/li>\n<li>Cambiar la cantidad de RAM en una PC f\u00edsica o virtual en la que se despliega el TrueConf Server ahora no requiere un nuevo registro posterior<\/li>\n<li>Una terminal SIP registrada en el TrueConf Server ahora obtiene una licencia SIP\/H.323\/RTSP solo despu\u00e9s de participar en una llamada o conferencia, no despu\u00e9s de registrarse en la plataforma de colaboraci\u00f3n de video.<\/li>\n<\/ul>\n<p>Consulte las <a href=\"https:\/\/trueconf.com\/products\/changelog.html#server\" target=\"_blank\" rel=\"noopener\">notas del lanzamiento<\/a> para ver la lista de todos los cambios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estamos felices de anunciar el TrueConf Server 5.3, la \u00faltima actualizaci\u00f3n de nuestra soluci\u00f3n insignia, que hace que el sistema de mensajer\u00eda corporativo est\u00e9 a\u00fan m\u00e1s disponible debido a una pol\u00edtica de licencias completamente renovada. Adem\u00e1s, la nueva versi\u00f3n introduce una nueva secci\u00f3n para gestionar extensiones de correo, funciones avanzadas de salas de espera y [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":2958,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[3],"class_list":["post-2927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualizacion","tag-trueconf-server","wpautop"],"_links":{"self":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/comments?post=2927"}],"version-history":[{"count":5,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2927\/revisions"}],"predecessor-version":[{"id":2961,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2927\/revisions\/2961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media\/2958"}],"wp:attachment":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media?parent=2927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/categories?post=2927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/tags?post=2927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}