{"id":2767,"date":"2023-09-01T16:22:11","date_gmt":"2023-09-01T14:22:11","guid":{"rendered":"https:\/\/trueconf.com/es-es/blog\/?p=2767"},"modified":"2025-10-28T12:25:37","modified_gmt":"2025-10-28T11:25:37","slug":"trueconf-mcu-2-0","status":"publish","type":"post","link":"https:\/\/trueconf.com/es-es/blog\/actualizacion\/trueconf-mcu-2-0","title":{"rendered":"Actualizaci\u00f3n importante del TrueConf MCU 2.0: nueva interfaz de usuario, funciones avanzadas de planificaci\u00f3n de conferencias, grabaci\u00f3n multicanal e historial de conferencias"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"wp-image-40399 size-full\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/mcu_es_1200x600.png\" alt=\"\" width=\"1200\" height=\"auto\" loading=\"lazy\" title=\"\"><\/p>\n<p style=\"text-align: justify;\">Nos complace anunciar el <b>TrueConf MCU 2.0<\/b>, la actualizaci\u00f3n principal de nuestro servidor de videoconferencias, basado en software, para terminales SIP\/H.323 heredados. La nueva versi\u00f3n trae una interfaz de panel de control completamente nueva y redise\u00f1ada, funciones avanzadas de planificaci\u00f3n de conferencias, grabaci\u00f3n multicanal y una nueva secci\u00f3n de historial de conferencias. \u00a1Lea nuestra descripci\u00f3n detallada para saber m\u00e1s!<\/p>\n<p><!--more--><br \/>\n&nbsp;<\/p>\n<p style=\"text-align: center;\"><a id=\"sbtn\" class=\"btn_blue btn_download big_text\" style=\"font-size: 23px;\" href=\"https:\/\/trueconf.com\/es\/productos\/mcu.html\" target=\"_blank\" rel=\"noopener noreferrer\">Descargar gratis<\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\"><b>Antes de actualizar a la versi\u00f3n TrueConf MCU 2.0, es necesario desinstale la versi\u00f3n anterior de su PC y que exporte los datos de antemano. Siga nuestra <a href=\"https:\/\/docs.trueconf.com\/mcu\/en\/update\/\" target=\"_blank\" rel=\"noopener\">gu\u00eda<\/a> detallada para obtener m\u00e1s informaci\u00f3n.<\/b><\/div>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Lista de los sistemas operativos compatibles<\/h2>\n<ul>\n<li>Debain 10<\/li>\n<li>Debian 11<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Lista de los hipervisores compatibles<\/h2>\n<ul>\n<li>VMWare ESXi 6.5<\/li>\n<li>KVM<\/li>\n<li>VirtualBox<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Historia de conferencia<\/h2>\n<p style=\"text-align: justify;\">Hemos agregado una nueva secci\u00f3n <b>Historial<\/b>, que muestra la lista de conferencias celebradas en el servidor de videoconferencia y sus anal\u00edticas detalladas.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/1_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/1_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">Luego de seleccionar la sesi\u00f3n deseada, podr\u00e1 ver un cronograma detallado de la actividad de los participantes y al hacer click en un segmento de tiempo se abrir\u00e1 m\u00e1s informaci\u00f3n: tiempos de conexi\u00f3n y desconexi\u00f3n, as\u00ed como los motivos por los cuales el usuario abandon\u00f3 la conferencia (desconexi\u00f3n iniciada por el participante, desconexi\u00f3n iniciada por el moderador, no se pudo llamar).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/2_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/2_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Grabaci\u00f3n de reuni\u00f3n multicanal<\/h2>\n<p style=\"text-align: justify;\">Para conferencias con varios dise\u00f1os de video, ahora puede habilitar la grabaci\u00f3n multicanal. Simplemente haga click en el bot\u00f3n de grabaci\u00f3n en la conferencia en curso y seleccione los dise\u00f1os que desea grabar.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/3_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/3_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">Cada dise\u00f1o para el que est\u00e1 habilitada la grabaci\u00f3n se guarda como un archivo .MP4 independiente<\/div>\n<h2 style=\"text-align: justify;\">Clasificaci\u00f3n de las conferencias<\/h2>\n<p style=\"text-align: justify;\">En la secci\u00f3n <b>Conferencias<\/b>, ahora puede organizar alfab\u00e9ticamente las reuniones en l\u00ednea activas e inactivas y elegir mostrar s\u00f3lo <b>sus conferencias<\/b> o <b>todas<\/b>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/4_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/4_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"font-size: 155%;\">Funciones avanzadas de planificaci\u00f3n de conferencias<\/h2>\n<p style=\"text-align: justify;\">A partir del TrueConf MCU 2.0, se redise\u00f1\u00f3 la interfaz del panel de control del servidor de videoconferencias, incluida la interfaz de planificaci\u00f3n de conferencias y sus nuevas funciones.<\/p>\n<h3 style=\"text-align: justify;\">Nombre y ruta<\/h3>\n<p style=\"text-align: justify;\">Hemos agregado la capacidad de personalizar la ruta, el identificador principal para conectarse a las conferencias. Anteriormente era el ID, un identificador adicional que constaba \u00fanicamente de d\u00edgitos. Ahora el propietario puede configurar manualmente cualquier identificador arbitrario que consista en d\u00edgitos, letras latinas, guiones y guiones bajos; simplemente ingr\u00e9selo en el campo o haga click en el icono <img decoding=\"async\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/image-3.png\" alt=\"\" width=\"32\" height=\"auto\" class=\"alignnone size-full wp-image-48581\" loading=\"lazy\" title=\"\">.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/5_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/5_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\">De forma predeterminada, la ruta es id\u00e9ntica al nombre de la conferencia, al cambiarlo tambi\u00e9n se cambiar\u00e1 su ruta<\/div>\n<p style=\"text-align: justify;\">Ahora puede usar el ID de la conferencia para conectarse usando DTMF. Simplemente llame al TrueConf MCU e ingrese el ID de la sesi\u00f3n de videoconferencia requerida.<\/p>\n<h3 style=\"text-align: justify;\">Configurar un PIN para conectarse a la conferencia<\/h3>\n<p style=\"text-align: justify;\">Al crear una conferencia, ahora puede protegerla adicionalmente con un PIN, antes el ID de la conferencia serv\u00eda como PIN.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/6_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/6_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h3 style=\"text-align: justify;\">Configurar la conexi\u00f3n mediante un enlace<\/h3>\n<p style=\"text-align: justify;\">Ahora puede configurar el acceso a la conferencia mediante un enlace, utilizando el par\u00e1metro correspondiente en la configuraci\u00f3n principal de la conferencia. Anteriormente, si se establec\u00eda un ID para la conferencia, la conexi\u00f3n mediante un enlace siempre estaba disponible.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/7_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/7_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h3 style=\"text-align: justify;\">Mostrar v\u00eddeo del usuario en el dise\u00f1o<\/h3>\n<p style=\"text-align: justify;\">El propietario de la conferencia ahora puede personalizar la visualizaci\u00f3n de las ventanas de v\u00eddeo de los usuarios en el dise\u00f1o de sus pantallas:<\/p>\n<ul>\n<li><b>Autom\u00e1ticamente.<\/b> La necesidad de mostrar la ventana de v\u00eddeo de un usuario se determina autom\u00e1ticamente.<\/li>\n<li><b>Mostrar.<\/b> La ventana de v\u00eddeo del usuario se muestra en el dise\u00f1o del usuario.<\/li>\n<li><b>No mostrar para el orador activo.<\/b> La ventana de video del usuario no aparece en el dise\u00f1o del usuario cuando hay actividad de voz y un espacio con un orador activo.<\/li>\n<li><b>No mostrar para todos.<\/b> La ventana de v\u00eddeo del usuario no aparece en el dise\u00f1o del usuario.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/8_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/8_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h3 style=\"text-align: justify;\">Configurar los par\u00e1metros de inicio de llamada<\/h3>\n<p style=\"text-align: justify;\">Ahora, al programar una conferencia, puede desactivar las llamadas autom\u00e1ticas a los participantes agregados al inicio de la conferencia. Puede agregarlos durante la reuni\u00f3n en l\u00ednea.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/9_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/9_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h3 style=\"text-align: justify;\">Dise\u00f1os para grupos de usuarios<\/h3>\n<p style=\"text-align: justify;\">Al planificar una conferencia, en la secci\u00f3n <b>Dise\u00f1os<\/b>, ahora puede configurar el dise\u00f1o para un grupo de usuarios agregados a la lista de participantes. Simplemente haga click en el bot\u00f3n <b>Agregar<\/b>, seleccione a los participantes y personalice el dise\u00f1o.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-2767 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/10_es.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1909\" height=\"940\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/10_es.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/10_es.jpg 1909w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/10_es-690x340.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/10_es-1024x504.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/10_es-768x378.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/10_es-1536x756.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/10_es-290x143.jpg 290w\" sizes=\"auto, (max-width: 1909px) 100vw, 1909px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/11_es.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1909\" height=\"940\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/11_es.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/11_es.jpg 1909w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/11_es-690x340.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/11_es-1024x504.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/11_es-768x378.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/11_es-1536x756.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/11_es-290x143.jpg 290w\" sizes=\"auto, (max-width: 1909px) 100vw, 1909px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<h3 style=\"text-align: justify;\">Agregar usuarios antes de que comience la conferencia sin ingresarlos en la libreta de direcciones<\/h3>\n<p style=\"text-align: justify;\">Hemos agregado la posibilidad de invitar preliminarmente, a una conferencia, a usuarios que no est\u00e1n en la libreta de direcciones. El bot\u00f3n correspondiente se muestra en la pesta\u00f1a <b>Informaci\u00f3n<\/b> en la etapa de planificaci\u00f3n de la conferencia.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-2 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-2 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-2' class='gallery galleryid-2767 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/12_es.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1910\" height=\"940\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/12_es.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/12_es.jpg 1910w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/12_es-690x340.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/12_es-1024x504.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/12_es-768x378.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/12_es-1536x756.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/12_es-290x143.jpg 290w\" sizes=\"auto, (max-width: 1910px) 100vw, 1910px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/13_es.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-2\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1909\" height=\"940\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/13_es.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/13_es.jpg 1909w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/13_es-690x340.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/13_es-1024x504.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/13_es-768x378.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/13_es-1536x756.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/13_es-290x143.jpg 290w\" sizes=\"auto, (max-width: 1909px) 100vw, 1909px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<h2 style=\"text-align: justify;\">Roles de administrador y usuario<\/h2>\n<p style=\"text-align: justify;\">Los administradores del TrueConf MCU 2.0 ahora pueden asignar usuarios agregados a la libreta de direcciones como <b>Administradores<\/b> u <b>Operadores<\/b> del servidor de videoconferencias.<\/p>\n<p style=\"text-align: justify;\">El administrador tiene acceso a todas las funciones del panel de control del TrueConf MCU. El operador tiene acceso a la creaci\u00f3n de cuentas de usuario, planificaci\u00f3n y conferencias, pero no tiene acceso a la configuraci\u00f3n de administraci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/14_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/14_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Configuraci\u00f3n de m\u00faltiples direcciones SIP\/H.323 para cada contacto<\/h2>\n<p style=\"text-align: justify;\">Ahora se puede configurar cualquier n\u00famero de direcciones SIP\/H.323 para cada contacto. Anteriormente s\u00f3lo estaba disponible una direcci\u00f3n SIP y una direcci\u00f3n H.323. La llamada se realiza a las direcciones especificadas del usuario una por una hasta que es aceptada. Esto le permite automatizar el proceso de marcado y acelerar la b\u00fasqueda de un dispositivo que pueda usarse para recibir la llamada.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/15_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/15_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">En cascada para usuarios seleccionados<\/h2>\n<p style=\"text-align: justify;\">Al agregar o editar la direcci\u00f3n de un contacto en la libreta de direcciones y al agregar a un participante de la conferencia por direcci\u00f3n, ahora puede habilitar la conexi\u00f3n <b>En Cascada<\/b> para este contacto. Esta caracter\u00edstica evita que su propio video se muestre en el dise\u00f1o de la pantalla del usuario seleccionado.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/16_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/16_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Estado de usuario: Ocupado<\/h2>\n<p style=\"text-align: justify;\">En la libreta de direcciones, el estado correspondiente \u2014 <b>Ocupado<\/b> \u2014 ahora se muestra junto al nombre del usuario que se encuentra actualmente en la conferencia.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/17_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/17_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Reproducci\u00f3n de archivos de v\u00eddeo en bucle<\/h2>\n<p style=\"text-align: justify;\">Los usuarios de TrueConf MCU 2.0, ahora no solo pueden compartir archivos de video en la conferencia, sino tambi\u00e9n iniciar la reproducci\u00f3n en bucle con el bot\u00f3n correspondiente en la ventana para compartir contenido. Esto ahorrar\u00e1 tiempo y automatizar\u00e1 el proceso de gesti\u00f3n de v\u00eddeo en una conferencia activa.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/18_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/18_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Modo mejorado de detecci\u00f3n de actividad de voz<\/h2>\n<p style=\"text-align: justify;\">En el TrueConf MCU 2.0, hemos agregado la capacidad de personalizar el modo de detecci\u00f3n de actividad de voz. El propietario de la conferencia ahora puede elegir c\u00f3mo se mostrar\u00e1 el orador activo: en una <b>ventana designada<\/b> o en <b>pantalla completa<\/b>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/19_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/19_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">Si hace click en el icono <img decoding=\"async\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/image-43.png\" alt=\"\" width=\"32\" height=\"auto\" class=\"alignnone size-full wp-image-48581\" loading=\"lazy\" title=\"\"> a la derecha del participante seleccionado, se fijar\u00e1 autom\u00e1ticamente en la ventana de dise\u00f1o principal.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/20_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/20_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Llamar a participantes desconectados con cambios de par\u00e1metros<\/h2>\n<p style=\"text-align: justify;\">Una vez iniciada una videoconferencia, su propietario puede cambiar sobre la marcha los par\u00e1metros de llamada de los participantes desconectados y volver a llamarles. Puede seleccionar el usuario en la lista de participantes desconectados, cambiar las configuraciones necesarias y haga click en <b>Conectar<\/b>.<\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-3 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-3 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-3' class='gallery galleryid-2767 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/21_es.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-3\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1909\" height=\"940\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/21_es.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/21_es.jpg 1909w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/21_es-690x340.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/21_es-1024x504.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/21_es-768x378.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/21_es-1536x756.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/21_es-290x143.jpg 290w\" sizes=\"auto, (max-width: 1909px) 100vw, 1909px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/22_es.jpg\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-3\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1909\" height=\"940\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/22_es.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/22_es.jpg 1909w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/22_es-690x340.jpg 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/22_es-1024x504.jpg 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/22_es-768x378.jpg 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/22_es-1536x756.jpg 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/09\/22_es-290x143.jpg 290w\" sizes=\"auto, (max-width: 1909px) 100vw, 1909px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p style=\"text-align: justify;\">Adem\u00e1s, la lista de participantes desconectados ahora tambi\u00e9n muestra el motivo de las llamadas no devueltas.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/23_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/23_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Descripci\u00f3n del contacto<\/h2>\n<p style=\"text-align: justify;\">Al ver o editar un contacto, ahora puede agregar una breve descripci\u00f3n, que se mostrar\u00e1 al ver la informaci\u00f3n del contacto en el panel de control del TrueConf MCU.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/24_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/24_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Capacidades avanzadas de exportaci\u00f3n de datos<\/h2>\n<p style=\"text-align: justify;\">El administrador del servidor de videoconferencias ahora puede exportar, tanto la base de datos completa, como los par\u00e1metros individuales.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/25_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/25_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Sincronizaci\u00f3n de fecha y hora<\/h2>\n<p style=\"text-align: justify;\">El administrador del TrueConf MCU 2.0 ahora puede configurar la sincronizaci\u00f3n de la fecha y la hora con el servidor NTP. Especifique los servidores NTP y el per\u00edodo de sincronizaci\u00f3n en la configuraci\u00f3n de <b>Fecha y Hora<\/b>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/26_es.jpg\" data-rel=\"lightbox-gallery-gR8OvH4T\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/09\/26_es.jpg\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<h2 style=\"text-align: justify;\">Otras actualizaciones \u00fatiles<\/h2>\n<ul>\n<li>Ahora, cuando crea una conferencia, su nombre se genera autom\u00e1ticamente en el formato <b>Conf_XXXXXXXXXXXXXXX<\/b>, donde XXXXXXXXXXXXXXX son n\u00fameros generados aleatoriamente. El propietario de la conferencia podr\u00e1 cambiar su nombre antes del inicio o durante el evento en l\u00ednea.<\/li>\n<li>Al agregar a un usuario a una direcci\u00f3n que pertenece a uno de los contactos de la libreta de direcciones, ahora se muestra una indicaci\u00f3n contextual con el contacto encontrado.<\/li>\n<li>Al agregar la direcci\u00f3n de un contacto que ya particip\u00f3 en conferencias en su TrueConf MCU a la libreta de direcciones, se muestra una indicaci\u00f3n contextual con la direcci\u00f3n completa.<\/li>\n<li>Hemos agregado la posibilidad de restablecer el TrueConf MCU a la configuraci\u00f3n de f\u00e1brica en la secci\u00f3n <b>Administraci\u00f3n \u2014 Eliminaci\u00f3n de datos<\/b>.<\/li>\n<li>Hemos agregado API para la administraci\u00f3n del servidor, la documentaci\u00f3n se puede encontrar en <direcci\u00f3n IP de su MCU TrueConf>\/api\/doc.<\/li>\n<li>Se ha mejorado el rendimiento general y la estabilidad del servidor MCU.<\/li>\n<ul>\n","protected":false},"excerpt":{"rendered":"<p>Nos complace anunciar el TrueConf MCU 2.0, la actualizaci\u00f3n principal de nuestro servidor de videoconferencias, basado en software, para terminales SIP\/H.323 heredados. La nueva versi\u00f3n trae una interfaz de panel de control completamente nueva y redise\u00f1ada, funciones avanzadas de planificaci\u00f3n de conferencias, grabaci\u00f3n multicanal y una nueva secci\u00f3n de historial de conferencias. \u00a1Lea nuestra descripci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":2768,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[8],"class_list":["post-2767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualizacion","tag-trueconf-mcu","wpautop"],"_links":{"self":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/comments?post=2767"}],"version-history":[{"count":4,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2767\/revisions"}],"predecessor-version":[{"id":2801,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2767\/revisions\/2801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media\/2768"}],"wp:attachment":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media?parent=2767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/categories?post=2767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/tags?post=2767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}