{"id":2407,"date":"2023-03-22T11:40:12","date_gmt":"2023-03-22T10:40:12","guid":{"rendered":"https:\/\/trueconf.com/es-es/blog\/?p=2407"},"modified":"2025-10-28T12:27:06","modified_gmt":"2025-10-28T11:27:06","slug":"trueconf-group-1-1","status":"publish","type":"post","link":"https:\/\/trueconf.com/es-es/blog\/actualizacion\/trueconf-group-1-1","title":{"rendered":"TrueConf Group 1.1: Calendario, cambio r\u00e1pido de c\u00e1mara, transmisi\u00f3n de archivos de video y soporte para Visca a trav\u00e9s de IP"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group_1600x800_es.jpg\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-40399 size-full\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group_1600x800_es.jpg\" alt=\"\" width=\"1200\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">Conozca el <b><a href=\"https:\/\/trueconf.com\/es\/productos\/group.html\" target=\"_blank\" rel=\"noopener\">TrueConf Group<\/a> 1.1<\/b>, la \u00faltima actualizaci\u00f3n de nuestro punto final de videoconferencias, para salas de reuniones de cualquier tama\u00f1o, con el firmware actualizado. La nueva versi\u00f3n cuenta con un calendario con las pr\u00f3ximas reuniones y soporte para el protocolo Visca a trav\u00e9s de IP para el control de c\u00e1maras PTZ. Con el TrueConf Group 1.1, los usuarios pueden transmitir archivos de video durante una reuni\u00f3n y cambiar entre c\u00e1maras y preajustes sobre la marcha. \u00a1Lea nuestra descripci\u00f3n detallada para obtener m\u00e1s informaci\u00f3n!<\/p>\n<p><!--more--><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\"><b>Si desea actualizar el firmware de su TrueConf Group, comun\u00edquese con nuestro <a href=\"https:\/\/trueconf.com\/es\/soporte.html\" target=\"_blank\" rel=\"noopener\">soporte t\u00e9cnico<\/a>.<\/b><\/div>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Cambio r\u00e1pido entre c\u00e1maras y ajustes predeterminados<\/h2>\n<p style=\"text-align: justify;\">Con el TrueConf Group 1.1, es f\u00e1cil cambiar entre c\u00e1maras web y PTZ conectadas al punto final de videoconferencias. En el panel de control de la conferencia, puede asignar hasta 10 posiciones con el \u00e1ngulo y la c\u00e1mara especificados. Esto le permitir\u00e1 cambiar entre m\u00faltiples escenas sobre la marcha en el panel de control de la conferencia o usando el control remoto.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_1.png\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_1.png\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"font-size: 155%;\">Libreta de direcciones: nuevas capacidades<\/h2>\n<h3 style=\"text-align: justify;\">Sincronizaci\u00f3n de contactos con el TrueConf Server y el TrueConf MCU<\/h3>\n<p style=\"text-align: justify;\">Los usuarios del TrueConf Group 1.1 ahora pueden iniciar sesi\u00f3n con una cuenta registrada en los sistemas de videoconferencias TrueConf Server o TrueConf MCU. Esto habilitar\u00e1 la sincronizaci\u00f3n y permitir\u00e1 agregar nuevos contactos desde la libreta de direcciones del sistema de videoconferencias correspondiente a la libreta de direcciones del TrueConf Group.<\/p>\n<p style=\"text-align: justify;\">Todos los cambios posteriores en la libreta de direcciones del TrueConf Server o del TrueConf MCU (agregar o eliminar contactos) se sincronizar\u00e1n con el TrueConf Group sin necesidad de una nueva autorizaci\u00f3n en el sistema de videoconferencias.<\/p>\n<p style=\"text-align: justify;\"> \n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 50%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-2407 gallery-columns-2 gallery-size-full'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_7.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_7.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_7.png 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_7-690x388.png 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_7-1024x576.png 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_7-768x432.png 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_7-1536x864.png 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_7-290x163.png 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_8.png\" title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-1\" data-rl_><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_8.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_8.png 1920w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_8-690x388.png 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_8-1024x576.png 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_8-768x432.png 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_8-1536x864.png 1536w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2023\/03\/group-11_8-290x163.png 290w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" title=\"\"><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n <\/p>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\">Hasta 5 direcciones de red para dispositivos SIP\/H323, NDI, RTSP y VNC en el perfil de usuario<\/h3>\n<p style=\"text-align: justify;\">Ahora, puede especificar hasta 5 direcciones de red de dispositivos SIP\/H.323, NDI, RTSP y VNC para cada contacto en la libreta de direcciones. Anteriormente, solo se pod\u00eda establecer una direcci\u00f3n de red para cada protocolo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_6.png\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_6.png\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Calendario con las pr\u00f3ximas reuniones<\/h2>\n<p style=\"text-align: justify;\">En abril de 2022, en el <a href=\"https:\/\/trueconf.com\/blog\/news\/trueconf-group-1-0-59.html\" target=\"_blank\" rel=\"noopener\">TrueConf Group 1.0.59<\/a>, presentamos la administraci\u00f3n remota del TrueConf Group a trav\u00e9s de la interfaz de l\u00ednea de comandos SSH. M\u00e1s tarde, en el <a href=\"https:\/\/trueconf.com\/blog\/news\/trueconf-group-1-0-60.html\" target=\"_blank\" rel=\"noopener\">TrueConf Group 1.0.60<\/a>, agregamos la capacidad de configurar la recepci\u00f3n de invitaciones a conferencias de ICS a trav\u00e9s de SSH y correo electr\u00f3nico.<\/p>\n<p style=\"text-align: justify;\">En la nueva versi\u00f3n, todas las invitaciones recibidas se agregan autom\u00e1ticamente a una nueva secci\u00f3n \u2014 <b>Calendario<\/b>. Ahora, puede realizar un seguimiento de las pr\u00f3ximas reuniones, as\u00ed como los cambios en las mismas en caso de aplazamiento o cancelaci\u00f3n del evento de conformidad con el protocolo iCalendar.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_10.png\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_10.png\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Fuentes RTSP, NDI y VNC como imagen o presentaci\u00f3n principal<\/h2>\n<p style=\"text-align: justify;\">En el TrueConf Group 1.1, puede usar hardware de red conectado a trav\u00e9s de RTSP, NDI y VNC como fuente de imagen principal. Solo necesita especificar el dispositivo correspondiente en <b>Settings<\/b> \u2014 <b>Video<\/b> \u2014 <b>Image capture<\/b>. El hardware debe agregarse a la libreta de direcciones de su terminal de videoconferencias con anticipaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_2.png\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_2.png\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">Los usuarios del TrueConf Group tambi\u00e9n pueden elegir dichos dispositivos como flujo de contenido (origen de la presentaci\u00f3n).<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_3.png\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_3.png\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Transmisi\u00f3n de archivos de video<\/h2>\n<p style=\"text-align: justify;\">Adem\u00e1s de mostrar im\u00e1genes .JPEG y .PNG, y presentaciones en .PDF, los usuarios del TrueConf Group 1.1 ahora pueden transmitir archivos de video durante la videoconferencia. Para hacerlo, cargue un archivo en formato .MKV, .MP4 o .TS en el panel de control de la presentaci\u00f3n y selecci\u00f3nelo para compartirlo como flujo de contenido. Todos los archivos descargados se almacenan en la memoria interna del TrueConf Group y permanecen disponibles para su uso posterior.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_4.png\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_4.png\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Compatibilidad con el protocolo Visca a trav\u00e9s de IP<\/h2>\n<p style=\"text-align: justify;\">En la versi\u00f3n 1.1, agregamos soporte para Visca a trav\u00e9s de  IP, protocolo para administrar c\u00e1maras PTZ en red. La interfaz de control de la c\u00e1mara IP, sobre Visca a trav\u00e9s de IP, no difiere del control de la c\u00e1mara conectada directamente. Puede seleccionar el protocolo correspondiente en el panel de control <b>Settings<\/b> \u2014 <b>Video<\/b>.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_5.png\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_5.png\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Aplicaci\u00f3n Android para la gesti\u00f3n remota<\/h2>\n<p style=\"text-align: justify;\">El punto final de videoconferencias de TrueConf Group (as\u00ed como el software de sala basado en PC TrueConf Room) ahora se puede controlar no solo a trav\u00e9s de la interfaz web, sino tambi\u00e9n mediante Room Discovery, una aplicaci\u00f3n especial dise\u00f1ada para Android.<\/p>\n<p style=\"text-align: justify;\">Con la aplicaci\u00f3n, puede encontrar autom\u00e1ticamente todos los sistemas de videoconferencias TrueConf Group y TrueConf Room, ubicados en la misma red WiFi, con su dispositivo Android y comenzar a gestionarlos sin tener que ingresar manualmente la URL. Si desea utilizar Room Discovery, comun\u00edquese con nuestro centro de <a href=\"https:\/\/trueconf.com\/es\/soporte.html\" target=\"_blank\" rel=\"noopener\">soporte t\u00e9cnico<\/a>.<\/p>\n<p><center><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_13.png\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-40399 size-full\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_13.png\" alt=\"\" width=\"270\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_11.png\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-40399 size-full\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_11.png\" alt=\"\" width=\"270\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/center><br \/>\n&nbsp;<\/p>\n<h2 style=\"text-align: justify;\">Otras mejoras \u00fatiles<\/h2>\n<ul>\n<li>En el TrueConf Group 1.0.59, se hizo posible utilizar el protocolo NDI para crear sesiones de transmisi\u00f3n en vivo con el punto final de videoconferencias. En el TrueConf Group 1.1, la transmisi\u00f3n NDI se puede iniciar haciendo click en el bot\u00f3n correspondiente en la <b>p\u00e1gina de administraci\u00f3n de la conferencia<\/b>.\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_9.png\" data-rel=\"lightbox-gallery-4QKeWJuZ\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-18607\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2023\/03\/group-11_9.png\" alt=\"\" width=\"auto\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<\/li>\n<li>Ahora, durante la transmisi\u00f3n NDI, no solo se transmite el dise\u00f1o de la grabaci\u00f3n, sino tambi\u00e9n el flujo de contenido (presentaci\u00f3n). Anteriormente, la transmisi\u00f3n solo estaba disponible durante una llamada o conferencia en curso, ahora se puede iniciar en cualquier momento.<\/li>\n<li>En <b>Settings<\/b> \u2014 <b>Recording and Streaming<\/b>, puede habilitar o deshabilitar la grabaci\u00f3n autom\u00e1tica de la transmisi\u00f3n para cada uno de los protocolos: <b>RTMP<\/b>, <b>SAP<\/b> y <b>NDI<\/b><\/li>\n<li>Hemos agregado soporte para el c\u00f3dec de audio Opus.<\/li>\n<li>Se ha aumentado el rendimiento general y la estabilidad del firmware del TrueConf Group.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Conozca el TrueConf Group 1.1, la \u00faltima actualizaci\u00f3n de nuestro punto final de videoconferencias, para salas de reuniones de cualquier tama\u00f1o, con el firmware actualizado. La nueva versi\u00f3n cuenta con un calendario con las pr\u00f3ximas reuniones y soporte para el protocolo Visca a trav\u00e9s de IP para el control de c\u00e1maras PTZ. Con el TrueConf [&hellip;]<\/p>\n","protected":false},"author":57,"featured_media":2425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[30],"class_list":["post-2407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualizacion","tag-trueconf-group","wpautop"],"_links":{"self":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/comments?post=2407"}],"version-history":[{"count":7,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2407\/revisions"}],"predecessor-version":[{"id":2442,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2407\/revisions\/2442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media\/2425"}],"wp:attachment":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media?parent=2407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/categories?post=2407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/tags?post=2407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}