{"id":2051,"date":"2022-11-07T11:39:01","date_gmt":"2022-11-07T10:39:01","guid":{"rendered":"https:\/\/trueconf.com/es-es/blog\/?p=2051"},"modified":"2025-10-28T12:28:53","modified_gmt":"2025-10-28T11:28:53","slug":"trueconf-group-1-0-61","status":"publish","type":"post","link":"https:\/\/trueconf.com/es-es/blog\/actualizacion\/trueconf-group-1-0-61","title":{"rendered":"TrueConf Group 1.0.61: compatibilidad con los est\u00e1ndares de red IEEE 802.1X e IEEE 802.1Q"},"content":{"rendered":"<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2022\/11\/group_1600x800_es-1.png\" data-rel=\"lightbox-gallery-LD9DjvN1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-40399 size-full\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2022\/11\/group_1600x800_es-1.png\" alt=\"\" width=\"1200\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">Conozca el <b>TrueConf Group 1.0.61<\/b>, la \u00faltima actualizaci\u00f3n de nuestro punto final de videoconferencias para salas de reuniones de cualquier tama\u00f1o. La nueva versi\u00f3n brinda soporte para los est\u00e1ndares de red IEEE 802.1X e IEEE 802.1Q y muchas otras mejoras \u00fatiles.<\/p>\n<p><!--more--><\/p>\n<div class=\"marked_note marked_note--green\" style=\"text-align: justify;\"><b>Si desea actualizar el firmware de su TrueConf Group, comun\u00edquese con nuestro <a href=\"https:\/\/trueconf.com\/es\/soporte.html\" target=\"_blank\" rel=\"noopener\">soporte t\u00e9cnico<\/a>.<\/b><\/div>\n<h2 style=\"font-size:155%;\">Compatibilidad con los est\u00e1ndares de red IEEE 802.1X e IEEE 802.1Q<\/h2>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Las redes Ethernet compatibles con los est\u00e1ndares IEEE 802.1X e IEEE802.1Q garantizan una conexi\u00f3n segura y protegida. Puede encontrar estas opciones en la secci\u00f3n Ethernet del panel de control web.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2022\/11\/settings_ethernet_group_en.png\" data-rel=\"lightbox-gallery-LD9DjvN1\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"wp-image-40399 size-full\" style=\"border: 1px solid grey;\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2022\/11\/settings_ethernet_group_en.png\" alt=\"\" width=\"1200\" height=\"auto\" loading=\"lazy\" title=\"\"><\/a><\/p>\n<p style=\"text-align: justify;\">El est\u00e1ndar <b>IEEE 802.1X<\/b> permite a los usuarios del TrueConf Group autenticarse y conectarse a una red con dispositivos confiables. Puede establecer una identidad y una contrase\u00f1a, as\u00ed como especificar el m\u00e9todo de autenticaci\u00f3n EAP en la configuraci\u00f3n de IEEE 802.1X..<\/p>\n<p style=\"text-align: justify;\">El est\u00e1ndar <b>IEEE 802.1Q<\/b> transmite datos a trav\u00e9s de una VLAN dentro de la red Ethernet. Todos los dispositivos dentro de la misma VLAN pueden comunicarse entre s\u00ed a trav\u00e9s de un canal aislado, mientras est\u00e1n conectados a la LAN con otros dispositivos. En esta configuraci\u00f3n est\u00e1ndar, puede elegir en qu\u00e9 red virtual operar\u00e1 el TrueConf Group especificando el ID de la  VLAN.<\/p>\n<h2 style=\"font-size:155%;\">Otras actualizaciones y mejoras<\/h2>\n<p style=\"text-align: justify;\">\n<ul>\n<li>Hemos mejorado el mecanismo para recuperar paquetes de red perdidos entre varios puntos finales TrueConf Group, conectados a trav\u00e9s del protocolo SIP. Esto le permite compensar el 10% de los paquetes de red perdidos y, por lo tanto, aumentar la estabilidad de la conexi\u00f3n.<\/li>\n<li>En la versi\u00f3n <a href=\"https:\/\/trueconf.com\/blog\/news\/trueconf-group-1-0-59.html#Other_improvements\" target=\"_blank\" rel=\"noopener\">1.0.59<\/a>, agregamos soporte para VNC, un protocolo simple para acceso remoto a interfaces gr\u00e1ficas de usuario. Ahora, puede conectarse a una computadora de la red, con un servidor VNC preinstalado, utilizando la autenticaci\u00f3n de nombre de usuario y contrase\u00f1a.<\/li>\n<li>Hemos mejorado la compatibilidad con los dispositivos Cisco SIP\/H.323.<\/li>\n<li>Hemos solucionado un error que causaba que la indicaci\u00f3n de silencio del micr\u00f3fono y el altavoz a veces no se mostrara en la pantalla conectada al punto final de la videoconferencia.<\/li>\n<li>Tambi\u00e9n hemos aumentado el rendimiento general y la estabilidad del firmware del TrueConf Group.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Conozca el TrueConf Group 1.0.61, la \u00faltima actualizaci\u00f3n de nuestro punto final de videoconferencias para salas de reuniones de cualquier tama\u00f1o. La nueva versi\u00f3n brinda soporte para los est\u00e1ndares de red IEEE 802.1X e IEEE 802.1Q y muchas otras mejoras \u00fatiles.<\/p>\n","protected":false},"author":59,"featured_media":2052,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[30],"class_list":["post-2051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualizacion","tag-trueconf-group","wpautop"],"_links":{"self":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/comments?post=2051"}],"version-history":[{"count":4,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2051\/revisions"}],"predecessor-version":[{"id":2081,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/2051\/revisions\/2081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media\/2052"}],"wp:attachment":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media?parent=2051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/categories?post=2051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/tags?post=2051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}