{"id":1018,"date":"2021-09-23T18:25:18","date_gmt":"2021-09-23T16:25:18","guid":{"rendered":"https:\/\/trueconf.com/es-es/blog\/?p=1018"},"modified":"2025-10-28T12:46:43","modified_gmt":"2025-10-28T11:46:43","slug":"trueconf-server-4-7-3-codigos-qr-para-unirse-a-las-reuniones-desde-trueconf-room","status":"publish","type":"post","link":"https:\/\/trueconf.com/es-es/blog\/actualizacion\/trueconf-server-4-7-3-codigos-qr-para-unirse-a-las-reuniones-desde-trueconf-room","title":{"rendered":"TrueConf Server 4.7.3: C\u00f3digos QR para unirse a las reuniones desde TrueConf Room"},"content":{"rendered":"<p><a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2021\/09\/trueconf_server_4-7-3-1200x600-es.png\" data-rel=\"lightbox-gallery-PEadh2cL\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter wp-image-1019 \" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2021\/09\/trueconf_server_4-7-3-1200x600-es.png\" alt=\"\" width=\"1200\" height=\"601\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2021\/09\/trueconf_server_4-7-3-1200x600-es.png 1200w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2021\/09\/trueconf_server_4-7-3-1200x600-es-690x346.png 690w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2021\/09\/trueconf_server_4-7-3-1200x600-es-1024x513.png 1024w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2021\/09\/trueconf_server_4-7-3-1200x600-es-768x385.png 768w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2021\/09\/trueconf_server_4-7-3-1200x600-es-290x145.png 290w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p><span style=\"font-weight: 400;\">Nos complace presentar una actualizaci\u00f3n para TrueConf Server 4.7.3 que trae una estabilidad mejorada para su sistema de video colaboraci\u00f3n y hace mucho m\u00e1s f\u00e1cil unirse a reuniones desde TrueConf Room. \u00a1No olvide actualizar!<\/span><\/p>\n<p style=\"text-align: center;\"><a id=\"sbtn\" class=\"btn_blue btn_download big_text\" style=\"font-size: 23px;\" href=\"https:\/\/trueconf.com\/es\/productos\/servidor\/como-actualizar-el-trueconf-server.html\" target=\"_blank\" rel=\"noopener noreferrer\">Actualizar<\/a><!--more--><\/p>\n<h2><strong>C\u00f3digos QR para unirse a reuniones desde TrueConf Room<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Ahora cuando los usuarios acceden a una p\u00e1gina web de la conferencia desde dispositivos m\u00f3viles pueden hacer clic en el nuevo bot\u00f3n que mostrar\u00e1 un c\u00f3digo QR. S\u00f3lo tiene que escanear el c\u00f3digo QR con la c\u00e1mara conectada a la PC donde est\u00e1 instalado TrueConf Room y se unir\u00e1 autom\u00e1ticamente a la reuni\u00f3n.<a href=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2021\/09\/qr_room_es_anim.gif\" data-rel=\"lightbox-gallery-PEadh2cL\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-1023\" src=\"https:\/\/trueconf.com\/es\/blog\/wp-content\/uploads\/2021\/09\/qr_room_es_anim-264x470.gif\" alt=\"\" width=\"264\" height=\"470\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2021\/09\/qr_room_es_anim-264x470.gif 264w, https:\/\/trueconf.com/es-es/blog\/wp-content\/uploads\/2021\/09\/qr_room_es_anim-102x182.gif 102w\" sizes=\"auto, (max-width: 264px) 100vw, 264px\" \/><\/a><\/span><\/p>\n<h2><span style=\"font-weight: 400;\"><strong>Otras mejoras<\/strong>\u00a0<\/span><\/h2>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">La aplicaci\u00f3n<\/span><span style=\"font-weight: 400;\"> cliente TrueConf para Windows se ha actualizado a la versi\u00f3n 7.5.2.277.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Se ha corregido el error que pod\u00eda provocar degradaciones ocasionales de la calidad de video para los puntos finales SIP debido a la racionalizaci\u00f3n de la transferencia de datos desde TrueConf Server.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Se ha mejorado la compatibilidad con las \u00faltimas versiones de los navegadores basados en Chromium al unirse a las reuniones a trav\u00e9s de WebRTC.<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Nos complace presentar una actualizaci\u00f3n para TrueConf Server 4.7.3 que trae una estabilidad mejorada para su sistema de video colaboraci\u00f3n y hace mucho m\u00e1s f\u00e1cil unirse a reuniones desde TrueConf Room. \u00a1No olvide actualizar! Actualizar<\/p>\n","protected":false},"author":59,"featured_media":1020,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40],"tags":[3,6],"class_list":["post-1018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualizacion","tag-trueconf-server","tag-trueconf-server-free","wpautop"],"_links":{"self":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/1018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/comments?post=1018"}],"version-history":[{"count":5,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/1018\/revisions"}],"predecessor-version":[{"id":1315,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/posts\/1018\/revisions\/1315"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media\/1020"}],"wp:attachment":[{"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/media?parent=1018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/categories?post=1018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/trueconf.com/es-es/blog\/wp-json\/wp\/v2\/tags?post=1018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}